{"id":235,"date":"2024-02-16T23:52:09","date_gmt":"2024-02-16T22:52:09","guid":{"rendered":"https:\/\/carreras.uleam.edu.ec\/derecho\/?p=235"},"modified":"2024-02-24T16:31:19","modified_gmt":"2024-02-24T15:31:19","slug":"reinicio-de-contrasenas","status":"publish","type":"post","link":"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/reinicio-de-contrasenas\/","title":{"rendered":"REINICIO DE CONTRASE\u00d1AS"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/20\/talento-humano-de-la-carrera\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/reclutamiento.gif\" alt=\"\" class=\"wp-image-98 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/20\/talento-humano-de-la-carrera\/\" target=\"_blank\" rel=\"noreferrer noopener\">Talento Humano<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/informacion-de-la-carrera-de-derecho\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/informacion.gif\" alt=\"\" class=\"wp-image-100 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/informacion-de-la-carrera-de-derecho\/\" target=\"_blank\" rel=\"noreferrer noopener\">Informaci\u00f3n de la Carrera<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-center\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/normativas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/documento.gif\" alt=\"\" class=\"wp-image-99 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/normativas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Normativas y Documentos<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/servicios\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/servicio-al-cliente.gif\" alt=\"\" class=\"wp-image-102 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/servicios\/\" target=\"_blank\" rel=\"noreferrer noopener\">Servicios<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/23\/areas-academicas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/colegio.gif\" alt=\"\" class=\"wp-image-219 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/23\/areas-academicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c1reas Acad\u00e9micas<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/salas-ludicas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/sala-de-conferencias.gif\" alt=\"\" class=\"wp-image-226 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/salas-ludicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Salas L\u00fadicas<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-vertically-aligned-center\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/medios\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/video.gif\" alt=\"\" class=\"wp-image-101 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/medios\/\" target=\"_blank\" rel=\"noreferrer noopener\">Medios<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/noticias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/noticias.gif\" alt=\"\" class=\"wp-image-103 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-medium-font-size wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/24\/noticias\/\" target=\"_blank\" rel=\"noreferrer noopener\">Noticias<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/perfil.gif\" alt=\"\" class=\"wp-image-157 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-left has-black-color has-text-color has-link-color has-medium-font-size wp-elements-1e153fa60f639f15aab965bf6fe0579e wp-block-paragraph\"><strong><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/16\/matriculacion\/\" target=\"_blank\" rel=\"noreferrer noopener\">Activaci\u00f3n de cuentas<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/09\/carrera-de-derecho\/\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/salida.gif\" alt=\"\" class=\"wp-image-187 size-full\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-black-color has-text-color has-link-color has-medium-font-size wp-elements-78684c328ed6cafa71b2641e6672fb05 wp-block-paragraph\"><a href=\"https:\/\/carreras.uleam.edu.ec\/derecho\/2024\/02\/09\/carrera-de-derecho\/\">Regresar al Men\u00fa Principal<\/a><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/reiniciar.gif\" alt=\"\" class=\"wp-image-236 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-large-font-size wp-block-paragraph\"><strong>REINICIO DE CONTRASE\u00d1AS<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Se\u00f1ores estudiantes, esperando que se encuentren bien, le hacemos llegar este servicio para agilizar el proceso de matriculaci\u00f3n por: Activaci\u00f3n, p\u00e9rdida o olvido de contrase\u00f1as para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-large-font-size\">+ Aula Virtual<\/li>\n\n\n\n<li class=\"has-large-font-size\">+ Correo Institucional<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Escriban a cualquiera de los siguientes correos electr\u00f3nicos:<\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-de69fd188ffa87bc73233f7d5ef8235d wp-block-paragraph\"><a href=\"mailto:derechomatricula@gmail.com\">derechomatricula@gmail.com<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-vivid-cyan-blue-color has-text-color has-link-color has-large-font-size wp-elements-544bd05288d081bf2a47874af2cc5e36 wp-block-paragraph\"><a href=\"mailto:jerson.macias@uleam.edu.ec\">jerson.macias@uleam.edu.ec<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Estos correos son los \u00fanicos medios que est\u00e1n autorizados para recibir las solicitudes de reinicio de contrase\u00f1a.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Se est\u00e1 utilizando un sistema autom\u00e1tico que gestiona este servicio de manera mas eficiente, por lo que el mensaje tiene que enviarlo con el siguiente formato:<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-center has-very-light-gray-background-color has-background\" style=\"grid-template-columns:34% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/correo.gif\" alt=\"\" class=\"wp-image-237 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p class=\"has-cyan-bluish-gray-background-color has-background wp-block-paragraph\">Asunto: <span class=\"has-inline-color has-vivid-cyan-blue-color\">Reinicio de contrase\u00f1a<\/span>.*<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p class=\"has-text-align-center has-very-dark-gray-color has-pale-cyan-blue-background-color has-text-color has-background wp-block-paragraph\" style=\"font-size:17px\"><span class=\"has-inline-color has-very-dark-gray-color\"><em> <\/em>Cuerpo del mensaje: <\/span><\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background wp-block-paragraph\">Nombres: <span class=\"has-inline-color has-vivid-cyan-blue-color\">Sus dos nombres y apellidos<\/span>.*<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background wp-block-paragraph\">Curso: <span class=\"has-inline-color has-vivid-cyan-blue-color\">Curso que est\u00e1 ejerciendo.<\/span><\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background wp-block-paragraph\">C\u00e9dula: <span class=\"has-inline-color has-vivid-cyan-blue-color\">Su n\u00famero de c\u00e9dula<\/span>.*<\/p>\n\n\n\n<p class=\"has-pale-cyan-blue-background-color has-background wp-block-paragraph\">Problema: <span class=\"has-inline-color has-vivid-cyan-blue-color\">Reinicio de contrase\u00f1a para correo institucional, Aula Virtual o Ambas<\/span>.*<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:15px\">Nota: Los \u00edtem que est\u00e1n en asteriscos ( * ) son datos obligatorios.  Horario de Atenci\u00f3n de Lunes a Viernes de 13:00 a 18:00 y de 19:00 a 20:30<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center has-vivid-red-color has-pale-cyan-blue-background-color has-text-color has-background has-medium-font-size wp-block-paragraph\">ADJUNTAR FOTO COPIA DE C\u00c9DULA PARA VALIDEZ DEL PROCESO<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:30% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/sin-llamadas.gif\" alt=\"\" class=\"wp-image-241 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><em><span class=\"has-inline-color has-vivid-red-color\">No se receptan llamadas ni mensajes de texto a celular ni WhatsApp<\/span><\/em><\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-vivid-red-color has-cyan-bluish-gray-background-color has-text-color has-background has-medium-font-size wp-block-paragraph\">PROBLEMAS COMUNES:<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/carreras.uleam.edu.ec\/jurisprudencia\/wp-content\/uploads\/sites\/40\/2020\/06\/hndcodgccibemadm.png\" alt=\"\" class=\"wp-image-16103 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Una vez obtenida la nueva contrase\u00f1a&#8230;<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Una vez que tiene la nueva contrase\u00f1a, al ingresar al sistema del correo institucional, el sistema le pedir\u00e1 que ingrese la contrase\u00f1a anterior, <\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">donde colocar\u00e1 la CONTRASE\u00d1A TEMPORAL, all\u00ed mismo le pide que ingrese una nueva contrase\u00f1a (PERSONAL)  y que repita la nueva contrase\u00f1a. RECUERDE: Que la contrase\u00f1a que coloque como personal, debe tener m\u00ednimo 8 d\u00edgitos y debe contener letras entre may\u00fasculas y min\u00fasculas adem\u00e1s de n\u00fameros, ejemplo: EsTuDiO2020.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:20% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"http:\/\/carreras.uleam.edu.ec\/derecho\/wp-content\/uploads\/sites\/90\/2024\/02\/advertencia.gif\" alt=\"\" class=\"wp-image-251 size-full\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-medium-font-size wp-block-paragraph\">En caso que no puedan tener acceso al correo institucional o aula virtual, <span class=\"has-inline-color has-vivid-red-color\">a pesar de haber obtenido la nueva contrase\u00f1a,<\/span> puede deberse a que su cuenta est\u00e9 bloqueada, y esto se debe los siguientes factores:<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\" style=\"font-size:23px\">1) Falta de documentaci\u00f3n en la secretar\u00eda de la facultad, el cual pueden comunicarse al correo:<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Ab. Mariana Pinargote Alonzo.<\/strong> <strong>SECRETARIA<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:25px\"><strong>Correo: <a href=\"mailto:mariana.pinargote@uleam.edu.ec\" target=\"_blank\" rel=\"noreferrer noopener\">mariana.pinargote@uleam.edu.ec<\/a> <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px\">2) Problemas internos con el sistema deben comunicarse, y exponer el problema a:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:25px\"><a href=\"mailto:incidencias.diit@uleam.edu.ec\">incidencias.diit@<\/a><a rel=\"noreferrer noopener\" href=\"mailto:incidencias.diit@uleam.edu.ec\" target=\"_blank\">uleam<\/a><a href=\"mailto:incidencias.diit@uleam.edu.ec\">.edu.ec<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:23px\">3) Todo problema relacionado con el aula virtual en referencia a la subida de archivos, formularios, selecci\u00f3n de materias, etc. deben comunicar el problema al correo:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:25px\"><a href=\"mailto:incidencias.diit@uleam.edu.ec\">incidencias.diit@<\/a><a rel=\"noreferrer noopener\" href=\"mailto:incidencias.diit@uleam.edu.ec\" target=\"_blank\">uleam<\/a><a href=\"mailto:incidencias.diit@uleam.edu.ec\">.edu.ec<\/a><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:23px\">Ellos se comunicar\u00e1n con usted y tratar\u00e1n de resolver el problema lo antes posible.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Talento Humano Informaci\u00f3n de la Carrera Normativas y Documentos Servicios \u00c1reas Acad\u00e9micas Salas L\u00fadicas Medios Noticias Activaci\u00f3n de cuentas Regresar al Men\u00fa Principal REINICIO DE CONTRASE\u00d1AS Se\u00f1ores estudiantes, esperando que se encuentren bien, le hacemos llegar este servicio para agilizar [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_regular_price":[],"currency_symbol":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-235","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"acf":[],"post_slider_layout_featured_media_urls":{"thumbnail":"","post_slider_layout_landscape_large":"","post_slider_layout_portrait_large":"","post_slider_layout_square_large":"","post_slider_layout_landscape":"","post_slider_layout_portrait":"","post_slider_layout_square":"","full":""},"_links":{"self":[{"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/posts\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":15,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/posts\/235\/revisions"}],"predecessor-version":[{"id":462,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/posts\/235\/revisions\/462"}],"wp:attachment":[{"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/media?parent=235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/categories?post=235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carreras.uleam.edu.ec\/derecho\/wp-json\/wp\/v2\/tags?post=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}